{"id":2224,"date":"2025-01-22T01:49:45","date_gmt":"2025-01-22T01:49:45","guid":{"rendered":"https:\/\/synergyhomecare.com\/nc-raleigh-27609\/home-care-services"},"modified":"2025-01-22T01:49:45","modified_gmt":"2025-01-22T01:49:45","slug":"home-care-services","status":"publish","type":"page","link":"https:\/\/synergyhomecare.com\/nc-raleigh-27609\/home-care-services\/","title":{"rendered":"Home Care Services"},"content":{"rendered":"<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-master-page.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-2224","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Home Care Services - SYNERGY HomeCare of North Raleigh<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/synergyhomecare.com\/nc-raleigh-27609\/home-care-services\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Home Care Services - SYNERGY HomeCare of North Raleigh\" \/>\n<meta property=\"og:description\" content=\"&nbsp;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/synergyhomecare.com\/nc-raleigh-27609\/home-care-services\/\" \/>\n<meta property=\"og:site_name\" content=\"SYNERGY HomeCare of North Raleigh\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/synergyhomecare.com\\\/nc-raleigh-27609\\\/home-care-services\\\/\",\"url\":\"https:\\\/\\\/synergyhomecare.com\\\/nc-raleigh-27609\\\/home-care-services\\\/\",\"name\":\"Home Care Services - SYNERGY HomeCare of North Raleigh\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/synergyhomecare.com\\\/nc-raleigh-27609\\\/#website\"},\"datePublished\":\"2025-01-22T01:49:45+00:00\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/synergyhomecare.com\\\/nc-raleigh-27609\\\/home-care-services\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/synergyhomecare.com\\\/nc-raleigh-27609\\\/#website\",\"url\":\"https:\\\/\\\/synergyhomecare.com\\\/nc-raleigh-27609\\\/\",\"name\":\"SYNERGY HomeCare of North Raleigh\",\"description\":\"The highest quality in-home senior care. Available 24\\\/7 to serve your non-medical needs. Dedicated care for your loved ones.\",\"publisher\":{\"@id\":\"https:\\\/\\\/synergyhomecare.com\\\/nc-raleigh-27609\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/synergyhomecare.com\\\/nc-raleigh-27609\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/synergyhomecare.com\\\/nc-raleigh-27609\\\/#organization\",\"name\":\"SYNERGY HomeCare of North Raleigh\",\"url\":\"https:\\\/\\\/synergyhomecare.com\\\/nc-raleigh-27609\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/synergyhomecare.com\\\/nc-raleigh-27609\\\/home-care-services\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/synergyhomecare.com\\\/nc-raleigh-27609\\\/home-care-services\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/synergyhomecare.com\\\/nc-raleigh-27609\\\/home-care-services\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/synergyhomecare.com\\\/wp-content\\\/uploads\\\/Group-18049.svg\",\"contentUrl\":\"https:\\\/\\\/synergyhomecare.com\\\/wp-content\\\/uploads\\\/Group-18049.svg\",\"caption\":\"SYNERGY HomeCare of North Raleigh\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Home Care Services - SYNERGY HomeCare of North Raleigh","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/synergyhomecare.com\/nc-raleigh-27609\/home-care-services\/","og_locale":"en_US","og_type":"article","og_title":"Home Care Services - SYNERGY HomeCare of North Raleigh","og_description":"&nbsp;","og_url":"https:\/\/synergyhomecare.com\/nc-raleigh-27609\/home-care-services\/","og_site_name":"SYNERGY HomeCare of North Raleigh","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/synergyhomecare.com\/nc-raleigh-27609\/home-care-services\/","url":"https:\/\/synergyhomecare.com\/nc-raleigh-27609\/home-care-services\/","name":"Home Care Services - SYNERGY HomeCare of North Raleigh","isPartOf":{"@id":"https:\/\/synergyhomecare.com\/nc-raleigh-27609\/#website"},"datePublished":"2025-01-22T01:49:45+00:00","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/synergyhomecare.com\/nc-raleigh-27609\/home-care-services\/"]}]},{"@type":"WebSite","@id":"https:\/\/synergyhomecare.com\/nc-raleigh-27609\/#website","url":"https:\/\/synergyhomecare.com\/nc-raleigh-27609\/","name":"SYNERGY HomeCare of North Raleigh","description":"The highest quality in-home senior care. Available 24\/7 to serve your non-medical needs. Dedicated care for your loved ones.","publisher":{"@id":"https:\/\/synergyhomecare.com\/nc-raleigh-27609\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/synergyhomecare.com\/nc-raleigh-27609\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Organization","Place"],"@id":"https:\/\/synergyhomecare.com\/nc-raleigh-27609\/#organization","name":"SYNERGY HomeCare of North Raleigh","url":"https:\/\/synergyhomecare.com\/nc-raleigh-27609\/","logo":{"@id":"https:\/\/synergyhomecare.com\/nc-raleigh-27609\/home-care-services\/#local-main-organization-logo"},"image":{"@id":"https:\/\/synergyhomecare.com\/nc-raleigh-27609\/home-care-services\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/synergyhomecare.com\/nc-raleigh-27609\/home-care-services\/#local-main-organization-logo","url":"https:\/\/synergyhomecare.com\/wp-content\/uploads\/Group-18049.svg","contentUrl":"https:\/\/synergyhomecare.com\/wp-content\/uploads\/Group-18049.svg","caption":"SYNERGY HomeCare of North Raleigh"}]}},"_links":{"self":[{"href":"https:\/\/synergyhomecare.com\/nc-raleigh-27609\/wp-json\/wp\/v2\/pages\/2224","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/synergyhomecare.com\/nc-raleigh-27609\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/synergyhomecare.com\/nc-raleigh-27609\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/synergyhomecare.com\/nc-raleigh-27609\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/synergyhomecare.com\/nc-raleigh-27609\/wp-json\/wp\/v2\/comments?post=2224"}],"version-history":[{"count":0,"href":"https:\/\/synergyhomecare.com\/nc-raleigh-27609\/wp-json\/wp\/v2\/pages\/2224\/revisions"}],"wp:attachment":[{"href":"https:\/\/synergyhomecare.com\/nc-raleigh-27609\/wp-json\/wp\/v2\/media?parent=2224"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}